{"id":2699,"date":"2020-09-01T21:02:24","date_gmt":"2020-09-01T19:02:24","guid":{"rendered":"https:\/\/hauderer.de\/wordpress\/?p=2699"},"modified":"2020-09-01T21:02:26","modified_gmt":"2020-09-01T19:02:26","slug":"die-haudererhome-127","status":"publish","type":"post","link":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/","title":{"rendered":"Die Hauderer@Home &#8211; 127"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg\" alt=\"Margit Wehle-Heich\" class=\"wp-image-2700\" width=\"900\" height=\"1357\" srcset=\"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg 900w, https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT-300x452.jpg 300w, https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT-531x800.jpg 531w, https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT-768x1158.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption><strong>127_Margit Wehle-Heich- Ohne Titel<\/strong><\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[7],"tags":[212,233],"class_list":["post-2699","post","type-post","status-publish","format-standard","hentry","category-kunstwerke","tag-die-haudererhome","tag-margit-wehle-heich"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Hauderer@Home - 127 &#8211; Der Hauderer-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Hauderer@Home - 127 &#8211; Der Hauderer-Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Hauderer-Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DieHauderer\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T19:02:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-01T19:02:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5d2879d690e24e7cbdbd8ab7356b29f9\"},\"headline\":\"Die Hauderer@Home &#8211; 127\",\"datePublished\":\"2020-09-01T19:02:24+00:00\",\"dateModified\":\"2020-09-01T19:02:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/127_Wehle-Heich-OT.jpg\",\"keywords\":[\"Die Hauderer@Home\",\"Margit Wehle-Heich\"],\"articleSection\":[\"Kunstwerke\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/\",\"name\":\"Die Hauderer@Home - 127 &#8211; Der Hauderer-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/127_Wehle-Heich-OT.jpg\",\"datePublished\":\"2020-09-01T19:02:24+00:00\",\"dateModified\":\"2020-09-01T19:02:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/127_Wehle-Heich-OT.jpg\",\"contentUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/127_Wehle-Heich-OT.jpg\",\"width\":900,\"height\":1357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/2699\\\/die-haudererhome-127\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Hauderer@Home &#8211; 127\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\",\"name\":\"Der Hauderer-Blog\",\"description\":\"Ein Forum f\u00fcr Mitglieder und Besucher\",\"publisher\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\",\"name\":\"Die Hauderer\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hauderer-kpl-oR-final.jpg\",\"contentUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hauderer-kpl-oR-final.jpg\",\"width\":2362,\"height\":1697,\"caption\":\"Die Hauderer\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DieHauderer\",\"https:\\\/\\\/www.instagram.com\\\/die.hauderer\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5d2879d690e24e7cbdbd8ab7356b29f9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.hauderer.de\"],\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Hauderer@Home - 127 &#8211; Der Hauderer-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/","og_locale":"de_DE","og_type":"article","og_title":"Die Hauderer@Home - 127 &#8211; Der Hauderer-Blog","og_url":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/","og_site_name":"Der Hauderer-Blog","article_publisher":"https:\/\/www.facebook.com\/DieHauderer","article_published_time":"2020-09-01T19:02:24+00:00","article_modified_time":"2020-09-01T19:02:26+00:00","og_image":[{"url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg","type":"","width":"","height":""}],"author":"admin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#article","isPartOf":{"@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/"},"author":{"name":"admin","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/person\/5d2879d690e24e7cbdbd8ab7356b29f9"},"headline":"Die Hauderer@Home &#8211; 127","datePublished":"2020-09-01T19:02:24+00:00","dateModified":"2020-09-01T19:02:26+00:00","mainEntityOfPage":{"@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/hauderer.de\/wordpress\/#organization"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#primaryimage"},"thumbnailUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg","keywords":["Die Hauderer@Home","Margit Wehle-Heich"],"articleSection":["Kunstwerke"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/","url":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/","name":"Die Hauderer@Home - 127 &#8211; Der Hauderer-Blog","isPartOf":{"@id":"https:\/\/hauderer.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#primaryimage"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#primaryimage"},"thumbnailUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg","datePublished":"2020-09-01T19:02:24+00:00","dateModified":"2020-09-01T19:02:26+00:00","breadcrumb":{"@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#primaryimage","url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg","contentUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/09\/127_Wehle-Heich-OT.jpg","width":900,"height":1357},{"@type":"BreadcrumbList","@id":"https:\/\/hauderer.de\/wordpress\/2699\/die-haudererhome-127\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hauderer.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Die Hauderer@Home &#8211; 127"}]},{"@type":"WebSite","@id":"https:\/\/hauderer.de\/wordpress\/#website","url":"https:\/\/hauderer.de\/wordpress\/","name":"Der Hauderer-Blog","description":"Ein Forum f\u00fcr Mitglieder und Besucher","publisher":{"@id":"https:\/\/hauderer.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hauderer.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hauderer.de\/wordpress\/#organization","name":"Die Hauderer","url":"https:\/\/hauderer.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/08\/Hauderer-kpl-oR-final.jpg","contentUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/08\/Hauderer-kpl-oR-final.jpg","width":2362,"height":1697,"caption":"Die Hauderer"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DieHauderer","https:\/\/www.instagram.com\/die.hauderer\/"]},{"@type":"Person","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/person\/5d2879d690e24e7cbdbd8ab7356b29f9","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.hauderer.de"],"url":"https:\/\/hauderer.de\/wordpress\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/2699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2699"}],"version-history":[{"count":1,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/2699\/revisions"}],"predecessor-version":[{"id":2701,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/2699\/revisions\/2701"}],"wp:attachment":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}