{"id":6501,"date":"2024-04-13T12:09:26","date_gmt":"2024-04-13T10:09:26","guid":{"rendered":"https:\/\/hauderer.de\/wordpress\/?p=6501"},"modified":"2024-04-13T12:09:27","modified_gmt":"2024-04-13T10:09:27","slug":"ausstellung-von-silvia-zumpfe","status":"publish","type":"post","link":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/","title":{"rendered":"Ausstellung von Silvia Zumpfe"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1355\" src=\"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg\" alt=\"Silvia Zumpfe\" class=\"wp-image-6502\" srcset=\"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg 900w, https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24-300x452.jpg 300w, https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24-531x800.jpg 531w, https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24-768x1156.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4],"tags":[54,293],"class_list":["post-6501","post","type-post","status-publish","format-standard","hentry","category-ausstellungen","category-einladungen","tag-ausstellung","tag-silvia-zumpfe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ausstellung von Silvia Zumpfe &#8211; Der Hauderer-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausstellung von Silvia Zumpfe &#8211; Der Hauderer-Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Hauderer-Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DieHauderer\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T10:09:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-13T10:09:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5d2879d690e24e7cbdbd8ab7356b29f9\"},\"headline\":\"Ausstellung von Silvia Zumpfe\",\"datePublished\":\"2024-04-13T10:09:26+00:00\",\"dateModified\":\"2024-04-13T10:09:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/\"},\"wordCount\":4,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zumpfe-Ausstellung-KH24.jpg\",\"keywords\":[\"Ausstellung\",\"Silvia Zumpfe\"],\"articleSection\":[\"Ausstellungen\",\"Einladungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/\",\"name\":\"Ausstellung von Silvia Zumpfe &#8211; Der Hauderer-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zumpfe-Ausstellung-KH24.jpg\",\"datePublished\":\"2024-04-13T10:09:26+00:00\",\"dateModified\":\"2024-04-13T10:09:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zumpfe-Ausstellung-KH24.jpg\",\"contentUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Zumpfe-Ausstellung-KH24.jpg\",\"width\":900,\"height\":1355},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6501\\\/ausstellung-von-silvia-zumpfe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausstellung von Silvia Zumpfe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\",\"name\":\"Der Hauderer-Blog\",\"description\":\"Ein Forum f\u00fcr Mitglieder und Besucher\",\"publisher\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\",\"name\":\"Die Hauderer\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hauderer-kpl-oR-final.jpg\",\"contentUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hauderer-kpl-oR-final.jpg\",\"width\":2362,\"height\":1697,\"caption\":\"Die Hauderer\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DieHauderer\",\"https:\\\/\\\/www.instagram.com\\\/die.hauderer\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5d2879d690e24e7cbdbd8ab7356b29f9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.hauderer.de\"],\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausstellung von Silvia Zumpfe &#8211; Der Hauderer-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/","og_locale":"de_DE","og_type":"article","og_title":"Ausstellung von Silvia Zumpfe &#8211; Der Hauderer-Blog","og_url":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/","og_site_name":"Der Hauderer-Blog","article_publisher":"https:\/\/www.facebook.com\/DieHauderer","article_published_time":"2024-04-13T10:09:26+00:00","article_modified_time":"2024-04-13T10:09:27+00:00","og_image":[{"url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg","type":"","width":"","height":""}],"author":"admin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#article","isPartOf":{"@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/"},"author":{"name":"admin","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/person\/5d2879d690e24e7cbdbd8ab7356b29f9"},"headline":"Ausstellung von Silvia Zumpfe","datePublished":"2024-04-13T10:09:26+00:00","dateModified":"2024-04-13T10:09:27+00:00","mainEntityOfPage":{"@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/"},"wordCount":4,"commentCount":1,"publisher":{"@id":"https:\/\/hauderer.de\/wordpress\/#organization"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#primaryimage"},"thumbnailUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg","keywords":["Ausstellung","Silvia Zumpfe"],"articleSection":["Ausstellungen","Einladungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/","url":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/","name":"Ausstellung von Silvia Zumpfe &#8211; Der Hauderer-Blog","isPartOf":{"@id":"https:\/\/hauderer.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#primaryimage"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#primaryimage"},"thumbnailUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg","datePublished":"2024-04-13T10:09:26+00:00","dateModified":"2024-04-13T10:09:27+00:00","breadcrumb":{"@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#primaryimage","url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg","contentUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2024\/04\/Zumpfe-Ausstellung-KH24.jpg","width":900,"height":1355},{"@type":"BreadcrumbList","@id":"https:\/\/hauderer.de\/wordpress\/6501\/ausstellung-von-silvia-zumpfe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hauderer.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Ausstellung von Silvia Zumpfe"}]},{"@type":"WebSite","@id":"https:\/\/hauderer.de\/wordpress\/#website","url":"https:\/\/hauderer.de\/wordpress\/","name":"Der Hauderer-Blog","description":"Ein Forum f\u00fcr Mitglieder und Besucher","publisher":{"@id":"https:\/\/hauderer.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hauderer.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hauderer.de\/wordpress\/#organization","name":"Die Hauderer","url":"https:\/\/hauderer.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/08\/Hauderer-kpl-oR-final.jpg","contentUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/08\/Hauderer-kpl-oR-final.jpg","width":2362,"height":1697,"caption":"Die Hauderer"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DieHauderer","https:\/\/www.instagram.com\/die.hauderer\/"]},{"@type":"Person","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/person\/5d2879d690e24e7cbdbd8ab7356b29f9","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.hauderer.de"],"url":"https:\/\/hauderer.de\/wordpress\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/6501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6501"}],"version-history":[{"count":1,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/6501\/revisions"}],"predecessor-version":[{"id":6503,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/6501\/revisions\/6503"}],"wp:attachment":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/categories?post=6501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/tags?post=6501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}