{"id":6936,"date":"2026-04-21T17:32:48","date_gmt":"2026-04-21T15:32:48","guid":{"rendered":"https:\/\/hauderer.de\/wordpress\/?p=6936"},"modified":"2026-04-21T17:32:53","modified_gmt":"2026-04-21T15:32:53","slug":"naechstes-vereinstreffen","status":"publish","type":"post","link":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/","title":{"rendered":"N\u00e4chstes Vereinstreffen"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Das n\u00e4chste Hauderertreffen wird am 7. Mai ab 18 Uhr im Atelier Kaul in 55471 Keidelheim, Hauptstr 3 stattfinden. G\u00e4ste sind herzlich willkommen.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das n\u00e4chste Hauderertreffen wird am 7. Mai ab 18 Uhr im Atelier Kaul in 55471 Keidelheim, Hauptstr 3 stattfinden. G\u00e4ste sind herzlich willkommen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6936","post","type-post","status-publish","format-standard","hentry","category-dies-und-das"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e4chstes Vereinstreffen &#8211; Der Hauderer-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e4chstes Vereinstreffen &#8211; Der Hauderer-Blog\" \/>\n<meta property=\"og:description\" content=\"Das n\u00e4chste Hauderertreffen wird am 7. Mai ab 18 Uhr im Atelier Kaul in 55471 Keidelheim, Hauptstr 3 stattfinden. G\u00e4ste sind herzlich willkommen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Hauderer-Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DieHauderer\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T15:32:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T15:32:53+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5d2879d690e24e7cbdbd8ab7356b29f9\"},\"headline\":\"N\u00e4chstes Vereinstreffen\",\"datePublished\":\"2026-04-21T15:32:48+00:00\",\"dateModified\":\"2026-04-21T15:32:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/\"},\"wordCount\":24,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\"},\"articleSection\":[\"Dies und Das\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/\",\"name\":\"N\u00e4chstes Vereinstreffen &#8211; Der Hauderer-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#website\"},\"datePublished\":\"2026-04-21T15:32:48+00:00\",\"dateModified\":\"2026-04-21T15:32:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/6936\\\/naechstes-vereinstreffen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00e4chstes Vereinstreffen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\",\"name\":\"Der Hauderer-Blog\",\"description\":\"Ein Forum f\u00fcr Mitglieder und Besucher\",\"publisher\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#organization\",\"name\":\"Die Hauderer\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hauderer-kpl-oR-final.jpg\",\"contentUrl\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Hauderer-kpl-oR-final.jpg\",\"width\":2362,\"height\":1697,\"caption\":\"Die Hauderer\"},\"image\":{\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DieHauderer\",\"https:\\\/\\\/www.instagram.com\\\/die.hauderer\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/5d2879d690e24e7cbdbd8ab7356b29f9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.hauderer.de\"],\"url\":\"https:\\\/\\\/hauderer.de\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e4chstes Vereinstreffen &#8211; Der Hauderer-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/","og_locale":"de_DE","og_type":"article","og_title":"N\u00e4chstes Vereinstreffen &#8211; Der Hauderer-Blog","og_description":"Das n\u00e4chste Hauderertreffen wird am 7. Mai ab 18 Uhr im Atelier Kaul in 55471 Keidelheim, Hauptstr 3 stattfinden. G\u00e4ste sind herzlich willkommen.","og_url":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/","og_site_name":"Der Hauderer-Blog","article_publisher":"https:\/\/www.facebook.com\/DieHauderer","article_published_time":"2026-04-21T15:32:48+00:00","article_modified_time":"2026-04-21T15:32:53+00:00","author":"admin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/#article","isPartOf":{"@id":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/"},"author":{"name":"admin","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/person\/5d2879d690e24e7cbdbd8ab7356b29f9"},"headline":"N\u00e4chstes Vereinstreffen","datePublished":"2026-04-21T15:32:48+00:00","dateModified":"2026-04-21T15:32:53+00:00","mainEntityOfPage":{"@id":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/"},"wordCount":24,"commentCount":0,"publisher":{"@id":"https:\/\/hauderer.de\/wordpress\/#organization"},"articleSection":["Dies und Das"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/","url":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/","name":"N\u00e4chstes Vereinstreffen &#8211; Der Hauderer-Blog","isPartOf":{"@id":"https:\/\/hauderer.de\/wordpress\/#website"},"datePublished":"2026-04-21T15:32:48+00:00","dateModified":"2026-04-21T15:32:53+00:00","breadcrumb":{"@id":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hauderer.de\/wordpress\/6936\/naechstes-vereinstreffen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hauderer.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"N\u00e4chstes Vereinstreffen"}]},{"@type":"WebSite","@id":"https:\/\/hauderer.de\/wordpress\/#website","url":"https:\/\/hauderer.de\/wordpress\/","name":"Der Hauderer-Blog","description":"Ein Forum f\u00fcr Mitglieder und Besucher","publisher":{"@id":"https:\/\/hauderer.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hauderer.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hauderer.de\/wordpress\/#organization","name":"Die Hauderer","url":"https:\/\/hauderer.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/08\/Hauderer-kpl-oR-final.jpg","contentUrl":"https:\/\/hauderer.de\/wordpress\/wp-content\/uploads\/2020\/08\/Hauderer-kpl-oR-final.jpg","width":2362,"height":1697,"caption":"Die Hauderer"},"image":{"@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DieHauderer","https:\/\/www.instagram.com\/die.hauderer\/"]},{"@type":"Person","@id":"https:\/\/hauderer.de\/wordpress\/#\/schema\/person\/5d2879d690e24e7cbdbd8ab7356b29f9","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb9f71396624602db48c4f953ea26ec8533526b71ddf47b0b64b547072e3994b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.hauderer.de"],"url":"https:\/\/hauderer.de\/wordpress\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/6936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6936"}],"version-history":[{"count":1,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/6936\/revisions"}],"predecessor-version":[{"id":6938,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/posts\/6936\/revisions\/6938"}],"wp:attachment":[{"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/categories?post=6936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hauderer.de\/wordpress\/wp-json\/wp\/v2\/tags?post=6936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}